{"id":6651,"count":1,"description":"","link":"https:\/\/www.caldea.com\/blog\/tag\/spring-caldea\/?lang=en","name":"spring caldea","slug":"spring-caldea","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>spring caldea Archives | Caldea<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"spring caldea Archives | Caldea\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.caldea.com\/blog\/tag\/spring-caldea\/?lang=en\" \/>\n<meta property=\"og:site_name\" content=\"Caldea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.caldea.com\/blog\/tag\/spring-caldea\/?lang=en\",\"url\":\"https:\/\/www.caldea.com\/blog\/tag\/spring-caldea\/?lang=en\",\"name\":\"spring caldea Archives | Caldea\",\"isPartOf\":{\"@id\":\"https:\/\/www.caldea.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.caldea.com\/blog\/tag\/spring-caldea\/?lang=en#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.caldea.com\/blog\/tag\/spring-caldea\/?lang=en#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.caldea.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"spring caldea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.caldea.com\/blog\/#website\",\"url\":\"https:\/\/www.caldea.com\/blog\/\",\"name\":\"Caldea\",\"description\":\"Caldea Andorra | Termol\u00fadico, balneario termal, spa infantil\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.caldea.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"spring caldea Archives | Caldea","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"spring caldea Archives | Caldea","og_url":"https:\/\/www.caldea.com\/blog\/tag\/spring-caldea\/?lang=en","og_site_name":"Caldea","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.caldea.com\/blog\/tag\/spring-caldea\/?lang=en","url":"https:\/\/www.caldea.com\/blog\/tag\/spring-caldea\/?lang=en","name":"spring caldea Archives | Caldea","isPartOf":{"@id":"https:\/\/www.caldea.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.caldea.com\/blog\/tag\/spring-caldea\/?lang=en#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.caldea.com\/blog\/tag\/spring-caldea\/?lang=en#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.caldea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"spring caldea"}]},{"@type":"WebSite","@id":"https:\/\/www.caldea.com\/blog\/#website","url":"https:\/\/www.caldea.com\/blog\/","name":"Caldea","description":"Caldea Andorra | Termol\u00fadico, balneario termal, spa infantil","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.caldea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.caldea.com\/blog\/wp-json\/wp\/v2\/tags\/6651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caldea.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.caldea.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.caldea.com\/blog\/wp-json\/wp\/v2\/posts?tags=6651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}