{"id":14379,"date":"2022-10-18T09:13:56","date_gmt":"2022-10-18T07:13:56","guid":{"rendered":"https:\/\/www.caldea.com\/blog\/?p=14379"},"modified":"2022-10-18T09:30:19","modified_gmt":"2022-10-18T07:30:19","slug":"spa-restaurante","status":"publish","type":"post","link":"https:\/\/www.caldea.com\/blog\/spa-restaurante\/","title":{"rendered":"Escapada Spa y Restaurante en oto\u00f1o en Caldea"},"content":{"rendered":"<p align=\"JUSTIFY\"><span lang=\"es-ES\">Seguro que has o\u00eddo decir que el agua abre el apetito\u2026 Y no sin raz\u00f3n. Despu\u00e9s de un ba\u00f1o termal en nuestro spa, no hay nada mejor que recuperar la energ\u00eda con una comida o cena en uno de los restaurantes de Caldea. <\/span><\/p>\n<h2 class=\"\" style=\"color: #36454f; font-size: 22px; font-weight: 500; line-height: 1.41; margin-bottom: 5px;\"><span lang=\"es-ES\">Viaja por los sabores m\u00e1s ex\u00f3ticos del Siam Shiki <\/span><\/h2>\n<p align=\"JUSTIFY\"><span lang=\"es-ES\">El restaurante que queda m\u00e1s cerca de In\u00fau cuenta con una carta variada de especialidades de la cocina oriental. Ofrece platos japoneses como tempuras, teri-yakis, tatakis, nigiris, makis, chirashi o sashimi y tailandeses como ensaladas, sopas, carnes y mariscos. Te gustar\u00e1 cenar con vistas a la laguna interior de In\u00fau o al lado del impresionante acuario cil\u00edndrico. Si hace buen tiempo, puedes solicitar comer o cenar en la terraza exterior, rodeado de monta\u00f1as y con el rumor de las aguas termales de la laguna exterior.<br \/>\nPara venir al Siam Shiki no hace falta ba\u00f1arte, pero si deseas una experiencia completa que combine gastronom\u00eda y spa, te hemos preparado unos paquetes con men\u00fa y entrada, tanto para el Termol\u00fadico como para In\u00fau.<\/span><\/p>\n<p style=\"text-align: center;\" align=\"JUSTIFY\"><a class=\"maxbutton-11 maxbutton maxbutton-entradas-familiares\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.caldea.com\/termoludico\/entrada-restaurante-siam-shiki\"><span class='mb-text'>Termol\u00fadico y Siam Shiki<\/span><\/a><\/p>\n<p style=\"text-align: center;\" align=\"JUSTIFY\"><a class=\"maxbutton-9 maxbutton maxbutton-for-him\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.caldea.com\/inuu\/spa-restaurante-siam-shiki\"><span class='mb-text'>In\u00fau y Siam Shiki<\/span><\/a><\/p>\n<h2 class=\"\" style=\"color: #36454f; font-size: 22px; font-weight: 500; line-height: 1.41; margin-bottom: 5px;\"><span lang=\"es-ES\">Descubre la carta del Restaurante Blu<\/span><\/h2>\n<p align=\"JUSTIFY\"><span lang=\"es-ES\">Otra opci\u00f3n sin salir de Caldea es comer o cenar en el Restaurante Blu. Disfrutar\u00e1s de una carta o de un men\u00fa diario mediterr\u00e1neo con platos de cocina francesa. \u00a1Seguro que te encanta!<br \/>\nComo en el Siam Shiki, tambi\u00e9n disponemos de paquetes que incluyen la entrada y un men\u00fa en el Restaurante Blu. Aunque si ese d\u00eda no te apetece ba\u00f1arte, no hace falta acceder a las aguas termales para poder venir a comer o a cenar.<\/span><\/p>\n<p style=\"text-align: center;\" align=\"JUSTIFY\"><a class=\"maxbutton-9 maxbutton maxbutton-for-him\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.caldea.com\/termoludico\/oferta-entrada-cena-restaurante-blu\"><span class='mb-text'>Termol\u00fadico y Blu<\/span><\/a><\/p>\n<p style=\"text-align: center;\" align=\"JUSTIFY\"><a class=\"maxbutton-9 maxbutton maxbutton-for-him\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.caldea.com\/inuu\/entrada-menu-blu\"><span class='mb-text'>In\u00fau y Blu<\/span><\/a><\/p>\n<p>La particularidad del Restaurante Blu de Caldea es que dispone de una zona que te permite comer en ropa de ba\u00f1o. Por norma general, este espacio de \u201crestaurante acu\u00e1tico\u201d solo est\u00e1 disponible para comidas, por lo que es ideal para aprovechar al m\u00e1ximo tu tiempo al mediod\u00eda. Adem\u00e1s, los viernes y s\u00e1bados, cuando Caldea cierra a las 23.59 h, tambi\u00e9n ofrece esta opci\u00f3n para cenar. Consulta aqu\u00ed los <span style=\"color: #36454f;\"><a style=\"color: #36454f;\" href=\"https:\/\/www.caldea.com\/horarios-caldea\">horarios<\/a><\/span>.<\/p>\n<p align=\"JUSTIFY\"><span lang=\"es-ES\">Este oto\u00f1o tienes una raz\u00f3n m\u00e1s para venir a Caldea: combinar tu experiencia spa con alguno de nuestros restaurantes. Descubre todas las opciones que proponemos <span style=\"color: #36454f;\"><a style=\"color: #36454f;\" href=\"https:\/\/www.caldea.com\/oferta-restaurante-andorra\">aqu\u00ed<\/a><\/span>.<br \/>\n\u00bfQu\u00e9 te apetece hoy? \u00bfCon qu\u00e9 plato vas a empezar?<\/span><\/p>\n<p align=\"JUSTIFY\">\n","protected":false},"excerpt":{"rendered":"<p>Seguro que has o\u00eddo decir que el agua abre el apetito\u2026 Y no sin raz\u00f3n. Despu\u00e9s de un ba\u00f1o termal en nuestro spa, no hay nada mejor que recuperar la energ\u00eda con una comida o cena en uno de los restaurantes de Caldea. Viaja por los sabores m\u00e1s ex\u00f3ticos del Siam Shiki El restaurante que &hellip; <a href=\"https:\/\/www.caldea.com\/blog\/spa-restaurante\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> \u00abEscapada Spa y Restaurante en oto\u00f1o en Caldea\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":14386,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[177],"tags":[6466,247,6508,339,6469,1685,6470,253],"class_list":["post-14379","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ofertas","tag-blu-2","tag-caldea-2","tag-cocina-mediterranea","tag-inuu-2","tag-japones","tag-siam-shiki","tag-tailandes","tag-termoludico"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ven a Caldea y disfruta de planes de spa y restaurante<\/title>\n<meta name=\"description\" content=\"Este oto\u00f1o no te pierdas las ofertas spa y restaurante para comer en el Siam Shiki y el Blu y ba\u00f1arte en el Termol\u00fadico y In\u00fau.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.caldea.com\/blog\/spa-restaurante\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ven a Caldea y disfruta de planes de spa y restaurante\" \/>\n<meta property=\"og:description\" content=\"Este oto\u00f1o no te pierdas las ofertas spa y restaurante para comer en el Siam Shiki y el Blu y ba\u00f1arte en el Termol\u00fadico y In\u00fau.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.caldea.com\/blog\/spa-restaurante\/\" \/>\n<meta property=\"og:site_name\" content=\"Caldea\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-18T07:13:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-18T07:30:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dzhi65wojqlkc.cloudfront.net\/blog\/wp-content\/uploads\/2022\/10\/spa-restaurante.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"724\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Caldea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.caldea.com\/blog\/spa-restaurante\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.caldea.com\/blog\/spa-restaurante\/\"},\"author\":{\"name\":\"Caldea\",\"@id\":\"https:\/\/www.caldea.com\/blog\/#\/schema\/person\/6fd5f1dd5fe8962748f3a91bf3c1d394\"},\"headline\":\"Escapada Spa y Restaurante en oto\u00f1o en Caldea\",\"datePublished\":\"2022-10-18T07:13:56+00:00\",\"dateModified\":\"2022-10-18T07:30:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.caldea.com\/blog\/spa-restaurante\/\"},\"wordCount\":460,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.caldea.com\/blog\/spa-restaurante\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dzhi65wojqlkc.cloudfront.net\/blog\/wp-content\/uploads\/2022\/10\/spa-restaurante.jpg\",\"keywords\":[\"Blu\",\"caldea\",\"Cocina mediterr\u00e1nea\",\"inuu\",\"japon\u00e9s\",\"siam shiki\",\"tailand\u00e9s\",\"termol\u00fadico\"],\"articleSection\":[\"Ofertas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.caldea.com\/blog\/spa-restaurante\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.caldea.com\/blog\/spa-restaurante\/\",\"url\":\"https:\/\/www.caldea.com\/blog\/spa-restaurante\/\",\"name\":\"Ven a Caldea y disfruta de planes de spa y restaurante\",\"isPartOf\":{\"@id\":\"https:\/\/www.caldea.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.caldea.com\/blog\/spa-restaurante\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.caldea.com\/blog\/spa-restaurante\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dzhi65wojqlkc.cloudfront.net\/blog\/wp-content\/uploads\/2022\/10\/spa-restaurante.jpg\",\"datePublished\":\"2022-10-18T07:13:56+00:00\",\"dateModified\":\"2022-10-18T07:30:19+00:00\",\"author\":{\"@id\":\"https:\/\/www.caldea.com\/blog\/#\/schema\/person\/6fd5f1dd5fe8962748f3a91bf3c1d394\"},\"description\":\"Este oto\u00f1o no te pierdas las ofertas spa y restaurante para comer en el Siam Shiki y el Blu y ba\u00f1arte en el Termol\u00fadico y In\u00fau.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.caldea.com\/blog\/spa-restaurante\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.caldea.com\/blog\/spa-restaurante\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.caldea.com\/blog\/spa-restaurante\/#primaryimage\",\"url\":\"https:\/\/dzhi65wojqlkc.cloudfront.net\/blog\/wp-content\/uploads\/2022\/10\/spa-restaurante.jpg\",\"contentUrl\":\"https:\/\/dzhi65wojqlkc.cloudfront.net\/blog\/wp-content\/uploads\/2022\/10\/spa-restaurante.jpg\",\"width\":1024,\"height\":724,\"caption\":\"spa-restaurante\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.caldea.com\/blog\/spa-restaurante\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.caldea.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Escapada Spa y Restaurante en oto\u00f1o en Caldea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.caldea.com\/blog\/#website\",\"url\":\"https:\/\/www.caldea.com\/blog\/\",\"name\":\"Caldea\",\"description\":\"Caldea Andorra | Termol\u00fadico, balneario termal, spa infantil\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.caldea.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.caldea.com\/blog\/#\/schema\/person\/6fd5f1dd5fe8962748f3a91bf3c1d394\",\"name\":\"Caldea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.caldea.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a4673e559333068dbb03dfd36e74f226f690c9149b9074db9c18c5e60f326f74?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a4673e559333068dbb03dfd36e74f226f690c9149b9074db9c18c5e60f326f74?s=96&d=mm&r=g\",\"caption\":\"Caldea\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ven a Caldea y disfruta de planes de spa y restaurante","description":"Este oto\u00f1o no te pierdas las ofertas spa y restaurante para comer en el Siam Shiki y el Blu y ba\u00f1arte en el Termol\u00fadico y In\u00fau.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.caldea.com\/blog\/spa-restaurante\/","og_locale":"es_ES","og_type":"article","og_title":"Ven a Caldea y disfruta de planes de spa y restaurante","og_description":"Este oto\u00f1o no te pierdas las ofertas spa y restaurante para comer en el Siam Shiki y el Blu y ba\u00f1arte en el Termol\u00fadico y In\u00fau.","og_url":"https:\/\/www.caldea.com\/blog\/spa-restaurante\/","og_site_name":"Caldea","article_published_time":"2022-10-18T07:13:56+00:00","article_modified_time":"2022-10-18T07:30:19+00:00","og_image":[{"width":1024,"height":724,"url":"https:\/\/dzhi65wojqlkc.cloudfront.net\/blog\/wp-content\/uploads\/2022\/10\/spa-restaurante.jpg","type":"image\/jpeg"}],"author":"Caldea","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.caldea.com\/blog\/spa-restaurante\/#article","isPartOf":{"@id":"https:\/\/www.caldea.com\/blog\/spa-restaurante\/"},"author":{"name":"Caldea","@id":"https:\/\/www.caldea.com\/blog\/#\/schema\/person\/6fd5f1dd5fe8962748f3a91bf3c1d394"},"headline":"Escapada Spa y Restaurante en oto\u00f1o en Caldea","datePublished":"2022-10-18T07:13:56+00:00","dateModified":"2022-10-18T07:30:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.caldea.com\/blog\/spa-restaurante\/"},"wordCount":460,"commentCount":0,"image":{"@id":"https:\/\/www.caldea.com\/blog\/spa-restaurante\/#primaryimage"},"thumbnailUrl":"https:\/\/dzhi65wojqlkc.cloudfront.net\/blog\/wp-content\/uploads\/2022\/10\/spa-restaurante.jpg","keywords":["Blu","caldea","Cocina mediterr\u00e1nea","inuu","japon\u00e9s","siam shiki","tailand\u00e9s","termol\u00fadico"],"articleSection":["Ofertas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.caldea.com\/blog\/spa-restaurante\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.caldea.com\/blog\/spa-restaurante\/","url":"https:\/\/www.caldea.com\/blog\/spa-restaurante\/","name":"Ven a Caldea y disfruta de planes de spa y restaurante","isPartOf":{"@id":"https:\/\/www.caldea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.caldea.com\/blog\/spa-restaurante\/#primaryimage"},"image":{"@id":"https:\/\/www.caldea.com\/blog\/spa-restaurante\/#primaryimage"},"thumbnailUrl":"https:\/\/dzhi65wojqlkc.cloudfront.net\/blog\/wp-content\/uploads\/2022\/10\/spa-restaurante.jpg","datePublished":"2022-10-18T07:13:56+00:00","dateModified":"2022-10-18T07:30:19+00:00","author":{"@id":"https:\/\/www.caldea.com\/blog\/#\/schema\/person\/6fd5f1dd5fe8962748f3a91bf3c1d394"},"description":"Este oto\u00f1o no te pierdas las ofertas spa y restaurante para comer en el Siam Shiki y el Blu y ba\u00f1arte en el Termol\u00fadico y In\u00fau.","breadcrumb":{"@id":"https:\/\/www.caldea.com\/blog\/spa-restaurante\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.caldea.com\/blog\/spa-restaurante\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.caldea.com\/blog\/spa-restaurante\/#primaryimage","url":"https:\/\/dzhi65wojqlkc.cloudfront.net\/blog\/wp-content\/uploads\/2022\/10\/spa-restaurante.jpg","contentUrl":"https:\/\/dzhi65wojqlkc.cloudfront.net\/blog\/wp-content\/uploads\/2022\/10\/spa-restaurante.jpg","width":1024,"height":724,"caption":"spa-restaurante"},{"@type":"BreadcrumbList","@id":"https:\/\/www.caldea.com\/blog\/spa-restaurante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.caldea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Escapada Spa y Restaurante en oto\u00f1o en Caldea"}]},{"@type":"WebSite","@id":"https:\/\/www.caldea.com\/blog\/#website","url":"https:\/\/www.caldea.com\/blog\/","name":"Caldea","description":"Caldea Andorra | Termol\u00fadico, balneario termal, spa infantil","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.caldea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.caldea.com\/blog\/#\/schema\/person\/6fd5f1dd5fe8962748f3a91bf3c1d394","name":"Caldea","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.caldea.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a4673e559333068dbb03dfd36e74f226f690c9149b9074db9c18c5e60f326f74?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a4673e559333068dbb03dfd36e74f226f690c9149b9074db9c18c5e60f326f74?s=96&d=mm&r=g","caption":"Caldea"}}]}},"views":1585,"_links":{"self":[{"href":"https:\/\/www.caldea.com\/blog\/wp-json\/wp\/v2\/posts\/14379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caldea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caldea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caldea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caldea.com\/blog\/wp-json\/wp\/v2\/comments?post=14379"}],"version-history":[{"count":0,"href":"https:\/\/www.caldea.com\/blog\/wp-json\/wp\/v2\/posts\/14379\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caldea.com\/blog\/wp-json\/wp\/v2\/media\/14386"}],"wp:attachment":[{"href":"https:\/\/www.caldea.com\/blog\/wp-json\/wp\/v2\/media?parent=14379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caldea.com\/blog\/wp-json\/wp\/v2\/categories?post=14379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caldea.com\/blog\/wp-json\/wp\/v2\/tags?post=14379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}