{"id":12930,"date":"2022-05-03T07:55:22","date_gmt":"2022-05-03T05:55:22","guid":{"rendered":"https:\/\/www.caldea.com\/blog\/?p=12930"},"modified":"2022-05-13T12:29:45","modified_gmt":"2022-05-13T10:29:45","slug":"restaurante-siam-shiki-andorra","status":"publish","type":"post","link":"https:\/\/www.caldea.com\/blog\/restaurante-siam-shiki-andorra\/","title":{"rendered":"Spa y gastronom\u00eda: la mejor combinaci\u00f3n para esta primavera"},"content":{"rendered":"<h6 align=\"JUSTIFY\"><span lang=\"es-ES\" style=\"color: #36454f;\">Actualizaci\u00f3n 13\/05\/22 <\/span><\/h6>\n<p align=\"JUSTIFY\"><span lang=\"es-ES\">Prepara una escapada a Caldea tambi\u00e9n en primavera. In\u00fau contin\u00faa abierto mientras el Termol\u00fadico realiza su parada t\u00e9cnica. Aprovecha las buenas temperaturas para venir a conocer el spa solo para adultos de Caldea o para repetir visita y comer en el restaurante Siam Shiki.<br \/>\nDescubre nuestra<strong> oferta especial con entrada y men\u00fa v\u00e1lida solo hasta el 27 de mayo<\/strong>.<\/span><\/p>\n<h2 class=\"\" style=\"color: #36454f; font-size: 22px; font-weight: 500; line-height: 1.41; margin-bottom: 5px;\"><span lang=\"es-ES\">Empieza en In\u00fau<\/span><\/h2>\n<p align=\"JUSTIFY\"><span lang=\"es-ES\">La escapada empieza sin duda por el spa, tanto si vienes por la ma\u00f1ana como si vienes por la tarde. <strong>Sum\u00e9rgete en las aguas termales de In\u00fau<\/strong>, b\u00e1\u00f1ate en la laguna interior y masajea tu espalda gracias a los jets de agua a diferente presi\u00f3n. Descansa en el Berlingot mientras disfrutas de las vistas a la monta\u00f1a. Recarga vitamina D en la laguna exterior y rel\u00e1jate en el espacio de reactivaci\u00f3n de In\u00fau, en el ba\u00f1o turco, las duchas de contrastes y la sauna.<br \/>\n<strong>En primavera continuamos con los talleres<\/strong>. Te invitamos a probar el de cuencos tibetanos (todo un cl\u00e1sico) o el de Mindful Movements con los que saldr\u00e1s como nuev@. Consulta los horarios y el resto de actividades <span style=\"color: #36454f;\"><a style=\"color: #36454f;\" href=\"https:\/\/www.caldea.com\/inuu-talleres\">aqu\u00ed<\/a><\/span>. <\/span><\/p>\n<h2 class=\"\" style=\"color: #36454f; font-size: 22px; font-weight: 500; line-height: 1.41; margin-bottom: 5px;\"><span lang=\"es-ES\">Acaba en el restaurante Siam Shiki<\/span><\/h2>\n<p align=\"JUSTIFY\"><span lang=\"es-ES\">Despu\u00e9s de los beneficios de las aguas termales de In\u00fau no tendr\u00e1s que desplazarte para comer o cenar. Solo preoc\u00fapate por elegir si quieres una mesa con vistas al spa o aprovechar el buen tiempo para en la terraza lounge. El <strong>Siam Shiki es un restaurante de Andorra imprescindible si eres un amante de la cocina asi\u00e1tica<\/strong>. Su decoraci\u00f3n es moderna y relajante y est\u00e1 presidida por un enorme y singular acuario. La cocina, deliciosa, te ofrece un amplio abanico de platos de la cocina japonesa y tailandesa.<\/span><\/p>\n<h2 class=\"\" style=\"color: #36454f; font-size: 22px; font-weight: 500; line-height: 1.41; margin-bottom: 5px;\"><span lang=\"es-ES\">Oferta spa y men\u00fa <\/span><\/h2>\n<p align=\"JUSTIFY\"><span lang=\"es-ES\">Hasta el 27 de mayo de 2022, te proponemos una atractiva oferta de In\u00fau + Siam Shiki que incluye:<br \/>\n&#8211; <strong>Entrada durante 3 horas<\/strong> \u00fanicamente a las instalaciones de In\u00fau (recuerda que el Termol\u00fadico y Or\u00edgenes est\u00e1n cerrados hasta el 27 de mayo) sin restricci\u00f3n de hora de entrada.<br \/>\n&#8211; Para la hora de la comida o la cena (seg\u00fan prefieras), un <strong>men\u00fa completo en el restaurante Siam Shiki<\/strong> con un primer y un segundo plato y postre, a elegir entre japon\u00e9s o tailand\u00e9s. Toma nota de que las bebidas no est\u00e1n incluidas.<br \/>\n&#8211; <strong>Pr\u00e9stamo del material de ba\u00f1o<\/strong> (albornoz, toalla y chanclas).<br \/>\n&#8211; Acceso gratuito a los <strong>talleres<\/strong> programados que se realicen durante las 3 horas de entrada a In\u00fau. <\/span><\/p>\n<p align=\"JUSTIFY\"><a class=\"maxbutton-11 maxbutton maxbutton-entradas-familiares\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.caldea.com\/inuu\/entrada-menu-siam-shiki-oferta-especial\"><span class='mb-text'>Reserva In\u00fau y Siam Shiki<\/span><\/a><\/p>\n<p align=\"JUSTIFY\"><span lang=\"es-ES\">Un paquete ideal para los amantes de la gastronom\u00eda y el spa.<br \/>\nNo te lo pierdas y comprarlo ahora en nuestra web.<br \/>\n<\/span><\/p>\n<p align=\"JUSTIFY\">\n","protected":false},"excerpt":{"rendered":"<p>Actualizaci\u00f3n 13\/05\/22 Prepara una escapada a Caldea tambi\u00e9n en primavera. In\u00fau contin\u00faa abierto mientras el Termol\u00fadico realiza su parada t\u00e9cnica. Aprovecha las buenas temperaturas para venir a conocer el spa solo para adultos de Caldea o para repetir visita y comer en el restaurante Siam Shiki. Descubre nuestra oferta especial con entrada y men\u00fa v\u00e1lida &hellip; <a href=\"https:\/\/www.caldea.com\/blog\/restaurante-siam-shiki-andorra\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> \u00abSpa y gastronom\u00eda: la mejor combinaci\u00f3n para esta primavera\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":12954,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[177],"tags":[247,339,6469,6486,1685,6495,6470,253],"class_list":["post-12930","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ofertas","tag-caldea-2","tag-inuu-2","tag-japones","tag-primavera-2","tag-siam-shiki","tag-spa-solo-adultos","tag-tailandes","tag-termoludico"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Disfruta de una visita a In\u00fau y el restaurante Siam Shiki<\/title>\n<meta name=\"description\" content=\"Prepara una escapada de aguas termales y gastronom\u00eda: entrada a In\u00fau el spa solo para adultos de Caldea y men\u00fa en el restaurante Siam Shiki.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.caldea.com\/blog\/restaurante-siam-shiki-andorra\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Disfruta de una visita a In\u00fau y el restaurante Siam Shiki\" \/>\n<meta property=\"og:description\" content=\"Prepara una escapada de aguas termales y gastronom\u00eda: entrada a In\u00fau el spa solo para adultos de Caldea y men\u00fa en el restaurante Siam Shiki.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.caldea.com\/blog\/restaurante-siam-shiki-andorra\/\" \/>\n<meta property=\"og:site_name\" content=\"Caldea\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-03T05:55:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-13T10:29:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dzhi65wojqlkc.cloudfront.net\/blog\/wp-content\/uploads\/2022\/05\/restaurant-siam-shiki.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"824\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Caldea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.caldea.com\/blog\/restaurante-siam-shiki-andorra\/\",\"url\":\"https:\/\/www.caldea.com\/blog\/restaurante-siam-shiki-andorra\/\",\"name\":\"Disfruta de una visita a In\u00fau y el restaurante Siam Shiki\",\"isPartOf\":{\"@id\":\"https:\/\/www.caldea.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.caldea.com\/blog\/restaurante-siam-shiki-andorra\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.caldea.com\/blog\/restaurante-siam-shiki-andorra\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dzhi65wojqlkc.cloudfront.net\/blog\/wp-content\/uploads\/2022\/05\/restaurant-siam-shiki.jpg\",\"datePublished\":\"2022-05-03T05:55:22+00:00\",\"dateModified\":\"2022-05-13T10:29:45+00:00\",\"author\":{\"@id\":\"https:\/\/www.caldea.com\/blog\/#\/schema\/person\/8e600a189805305c91fffc834bd25ecf\"},\"description\":\"Prepara una escapada de aguas termales y gastronom\u00eda: entrada a In\u00fau el spa solo para adultos de Caldea y men\u00fa en el restaurante Siam Shiki.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.caldea.com\/blog\/restaurante-siam-shiki-andorra\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.caldea.com\/blog\/restaurante-siam-shiki-andorra\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.caldea.com\/blog\/restaurante-siam-shiki-andorra\/#primaryimage\",\"url\":\"https:\/\/dzhi65wojqlkc.cloudfront.net\/blog\/wp-content\/uploads\/2022\/05\/restaurant-siam-shiki.jpg\",\"contentUrl\":\"https:\/\/dzhi65wojqlkc.cloudfront.net\/blog\/wp-content\/uploads\/2022\/05\/restaurant-siam-shiki.jpg\",\"width\":1140,\"height\":824,\"caption\":\"restaurant-siam-shiki\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.caldea.com\/blog\/restaurante-siam-shiki-andorra\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.caldea.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spa y gastronom\u00eda: la mejor combinaci\u00f3n para esta primavera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.caldea.com\/blog\/#website\",\"url\":\"https:\/\/www.caldea.com\/blog\/\",\"name\":\"Caldea\",\"description\":\"Caldea Andorra | Termol\u00fadico, balneario termal, spa infantil\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.caldea.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.caldea.com\/blog\/#\/schema\/person\/8e600a189805305c91fffc834bd25ecf\",\"name\":\"Caldea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.caldea.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a4673e559333068dbb03dfd36e74f226f690c9149b9074db9c18c5e60f326f74?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a4673e559333068dbb03dfd36e74f226f690c9149b9074db9c18c5e60f326f74?s=96&d=mm&r=g\",\"caption\":\"Caldea\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Disfruta de una visita a In\u00fau y el restaurante Siam Shiki","description":"Prepara una escapada de aguas termales y gastronom\u00eda: entrada a In\u00fau el spa solo para adultos de Caldea y men\u00fa en el restaurante Siam Shiki.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.caldea.com\/blog\/restaurante-siam-shiki-andorra\/","og_locale":"es_ES","og_type":"article","og_title":"Disfruta de una visita a In\u00fau y el restaurante Siam Shiki","og_description":"Prepara una escapada de aguas termales y gastronom\u00eda: entrada a In\u00fau el spa solo para adultos de Caldea y men\u00fa en el restaurante Siam Shiki.","og_url":"https:\/\/www.caldea.com\/blog\/restaurante-siam-shiki-andorra\/","og_site_name":"Caldea","article_published_time":"2022-05-03T05:55:22+00:00","article_modified_time":"2022-05-13T10:29:45+00:00","og_image":[{"width":1140,"height":824,"url":"https:\/\/dzhi65wojqlkc.cloudfront.net\/blog\/wp-content\/uploads\/2022\/05\/restaurant-siam-shiki.jpg","type":"image\/jpeg"}],"author":"Caldea","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.caldea.com\/blog\/restaurante-siam-shiki-andorra\/","url":"https:\/\/www.caldea.com\/blog\/restaurante-siam-shiki-andorra\/","name":"Disfruta de una visita a In\u00fau y el restaurante Siam Shiki","isPartOf":{"@id":"https:\/\/www.caldea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.caldea.com\/blog\/restaurante-siam-shiki-andorra\/#primaryimage"},"image":{"@id":"https:\/\/www.caldea.com\/blog\/restaurante-siam-shiki-andorra\/#primaryimage"},"thumbnailUrl":"https:\/\/dzhi65wojqlkc.cloudfront.net\/blog\/wp-content\/uploads\/2022\/05\/restaurant-siam-shiki.jpg","datePublished":"2022-05-03T05:55:22+00:00","dateModified":"2022-05-13T10:29:45+00:00","author":{"@id":"https:\/\/www.caldea.com\/blog\/#\/schema\/person\/8e600a189805305c91fffc834bd25ecf"},"description":"Prepara una escapada de aguas termales y gastronom\u00eda: entrada a In\u00fau el spa solo para adultos de Caldea y men\u00fa en el restaurante Siam Shiki.","breadcrumb":{"@id":"https:\/\/www.caldea.com\/blog\/restaurante-siam-shiki-andorra\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.caldea.com\/blog\/restaurante-siam-shiki-andorra\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.caldea.com\/blog\/restaurante-siam-shiki-andorra\/#primaryimage","url":"https:\/\/dzhi65wojqlkc.cloudfront.net\/blog\/wp-content\/uploads\/2022\/05\/restaurant-siam-shiki.jpg","contentUrl":"https:\/\/dzhi65wojqlkc.cloudfront.net\/blog\/wp-content\/uploads\/2022\/05\/restaurant-siam-shiki.jpg","width":1140,"height":824,"caption":"restaurant-siam-shiki"},{"@type":"BreadcrumbList","@id":"https:\/\/www.caldea.com\/blog\/restaurante-siam-shiki-andorra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.caldea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Spa y gastronom\u00eda: la mejor combinaci\u00f3n para esta primavera"}]},{"@type":"WebSite","@id":"https:\/\/www.caldea.com\/blog\/#website","url":"https:\/\/www.caldea.com\/blog\/","name":"Caldea","description":"Caldea Andorra | Termol\u00fadico, balneario termal, spa infantil","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.caldea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.caldea.com\/blog\/#\/schema\/person\/8e600a189805305c91fffc834bd25ecf","name":"Caldea","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.caldea.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a4673e559333068dbb03dfd36e74f226f690c9149b9074db9c18c5e60f326f74?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a4673e559333068dbb03dfd36e74f226f690c9149b9074db9c18c5e60f326f74?s=96&d=mm&r=g","caption":"Caldea"}}]}},"views":1646,"_links":{"self":[{"href":"https:\/\/www.caldea.com\/blog\/wp-json\/wp\/v2\/posts\/12930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caldea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caldea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caldea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caldea.com\/blog\/wp-json\/wp\/v2\/comments?post=12930"}],"version-history":[{"count":0,"href":"https:\/\/www.caldea.com\/blog\/wp-json\/wp\/v2\/posts\/12930\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caldea.com\/blog\/wp-json\/wp\/v2\/media\/12954"}],"wp:attachment":[{"href":"https:\/\/www.caldea.com\/blog\/wp-json\/wp\/v2\/media?parent=12930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caldea.com\/blog\/wp-json\/wp\/v2\/categories?post=12930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caldea.com\/blog\/wp-json\/wp\/v2\/tags?post=12930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}